{"id":2096,"date":"2015-06-01T00:00:00","date_gmt":"2015-06-01T00:00:00","guid":{"rendered":"http:\/\/riverbank.aberdeen.sch.uk\/blogs\/wp-content\/uploads\/2015\/06\/10-300x200.jpg"},"modified":"2015-06-01T00:00:00","modified_gmt":"2015-06-01T00:00:00","slug":"10-300x200","status":"inherit","type":"attachment","link":"https:\/\/riverbank.aberdeen.sch.uk\/blogs\/10-300x200\/","title":{"rendered":"10-300&#215;200"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout"},"class_list":["post-2096","attachment","type-attachment","status-inherit","hentry"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/a6JM5L-xO","description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/riverbank.aberdeen.sch.uk\/blogs\/wp-content\/uploads\/2015\/06\/10-300x200.jpg?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/i0.wp.com\/riverbank.aberdeen.sch.uk\/blogs\/wp-content\/uploads\/2015\/06\/10-300x200.jpg?fit=300%2C200&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"\" data-attachment-id=\"2096\" data-permalink=\"https:\/\/riverbank.aberdeen.sch.uk\/blogs\/10-300x200\/\" data-orig-file=\"https:\/\/i0.wp.com\/riverbank.aberdeen.sch.uk\/blogs\/wp-content\/uploads\/2015\/06\/10-300x200.jpg?fit=300%2C200&amp;ssl=1\" data-orig-size=\"300,200\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"10-300&amp;#215;200\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riverbank.aberdeen.sch.uk\/blogs\/wp-content\/uploads\/2015\/06\/10-300x200.jpg?fit=300%2C200&amp;ssl=1\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":300,"height":200,"file":"2015\/06\/10-300x200.jpg","sizes":{"thumbnail":{"file":"10-300x200-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/riverbank.aberdeen.sch.uk\/blogs\/wp-content\/uploads\/2015\/06\/10-300x200.jpg?resize=150%2C150&ssl=1"},"medium":{"file":"10-300x200-300x200.jpg","width":300,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/riverbank.aberdeen.sch.uk\/blogs\/wp-content\/uploads\/2015\/06\/10-300x200.jpg?fit=300%2C200&ssl=1"},"post-thumbnail":{"file":"10-300x200-300x188.jpg","width":300,"height":188,"mime_type":"image\/jpeg","source_url":"https:\/\/riverbank.aberdeen.sch.uk\/blogs\/wp-content\/uploads\/2015\/06\/10-300x200-300x188.jpg"},"large-feature":{"file":"10-300x200-300x188.jpg","width":300,"height":188,"mime_type":"image\/jpeg","source_url":"https:\/\/riverbank.aberdeen.sch.uk\/blogs\/wp-content\/uploads\/2015\/06\/10-300x200-300x188.jpg"},"full":{"file":"10-300x200.jpg?fit=300%2C200&ssl=1","width":300,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/riverbank.aberdeen.sch.uk\/blogs\/wp-content\/uploads\/2015\/06\/10-300x200.jpg?fit=300%2C200&ssl=1"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":0}},"post":null,"source_url":"https:\/\/riverbank.aberdeen.sch.uk\/blogs\/wp-content\/uploads\/2015\/06\/10-300x200.jpg","_links":{"self":[{"href":"https:\/\/riverbank.aberdeen.sch.uk\/blogs\/wp-json\/wp\/v2\/media\/2096","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/riverbank.aberdeen.sch.uk\/blogs\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/riverbank.aberdeen.sch.uk\/blogs\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/riverbank.aberdeen.sch.uk\/blogs\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/riverbank.aberdeen.sch.uk\/blogs\/wp-json\/wp\/v2\/comments?post=2096"}]}}